{"id":1651,"date":"2018-01-08T10:22:50","date_gmt":"2018-01-08T16:22:50","guid":{"rendered":"https:\/\/restruct-lgmd-2021.pantheonsite.io\/?p=1651"},"modified":"2018-01-08T10:22:50","modified_gmt":"2018-01-08T16:22:50","slug":"jill-2","status":"publish","type":"post","link":"https:\/\/www.lgmd-info.org\/it\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/","title":{"rendered":"INDIVIDUO CON LGMD: Jill"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Intervista a LGMD Spotlight<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Nome<\/strong><\/span>:<span style=\"color: #000000;\">\u00a0 \u00a0 Jill\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<strong>Et\u00e0<\/strong>: 33 anni<a href=\"https:\/\/www.lgmd-info.org\/wp-content\/uploads\/2018\/01\/LGMD2i-Jill-W.png\"><img decoding=\"async\" class=\"lazyload size-medium wp-image-1650 alignright\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27169%27%20viewBox%3D%270%200%20300%20169%27%3E%3Crect%20width%3D%27300%27%20height%3D%27169%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.lgmd-info.org\/wp-content\/uploads\/2018\/01\/LGMD2i-Jill-W-300x169.png\" alt=\"\" width=\"300\" height=\"169\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Paese<\/strong>:    Stati Uniti<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Sottotipo LGMD<\/strong>:    LGMD2i<\/span><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>A che et\u00e0 \u00e8 stata fatta la diagnosi<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Mi \u00e8 stata diagnosticata all'et\u00e0 di 27 anni.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Quali sono stati i primi sintomi<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Alle elementari, ero sempre l'ultimo bambino a tagliare il traguardo in <\/span>palestra<span style=\"color: #000000;\">. Ricordo anche di aver dovuto abbandonare le attivit\u00e0 scolastiche a causa di dolorosi crampi alle gambe. Tuttavia, facevo parte della squadra di danza e avevo una <\/span>super normale<span style=\"color: #000000;\"> infanzia. Dopo la nascita del mio primo figlio nel 2008, all'et\u00e0 di 23 anni, ho iniziato a presentarmi al Pronto Soccorso con stanchezza e dolore a intervalli regolari. Ricordo di aver detto a mio marito: \"C'\u00e8 qualcosa che non va in me e un giorno capir\u00f2 cos'\u00e8\". Dopo la nascita della mia seconda figlia nel 2010, ho lottato con la fisicit\u00e0 di avere un bambino e un neonato. Non ero pi\u00f9 in grado di salire una rampa di scale senza grande sforzo. Pensavo ancora: \"Forse \u00e8 proprio cos\u00ec che si sentono le mamme stanche\". Poi, nel 2011, ho avuto una rabdomiolisi dopo aver preso un virus e aver avuto la febbre. Sono andata dal medico con una grave debolezza e il mio CPK era di 11.000. Questo ci ha finalmente portato sulla strada giusta e la diagnosi di LGMD2I \u00e8 stata scoperta. Come per molti di voi, la strada verso la diagnosi \u00e8 stata lunga.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Avete altri familiari affetti da LGMD:<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">No, sono omozigote recessivo, quindi entrambi i miei genitori erano portatori. Fortunatamente, mio fratello e mia sorella non ne sono affetti.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Quali sono, secondo lei, le sfide pi\u00f9 grandi da affrontare nella convivenza con la LGMD?<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Le mie bambine erano piccole quando mi \u00e8 stata diagnosticata la malattia. Un anno dopo a mio marito fu diagnosticato un cancro al cervello. Temevo che non sarei stata in grado di occuparmi della mia famiglia. Ho passato molte ore a preoccuparmi di quello che ci sarebbe successo. Cerco di rimanere nel momento e di godermi i bei momenti. Pu\u00f2 essere difficile mantenere la \"testa nel gioco\" e non anticipare il mio declino o lasciare che la frustrazione e il dolore mi mettano in difficolt\u00e0. <\/span>a<span style=\"color: #000000;\"> letto. Tuttavia, oggi sono qui. Mio marito \u00e8 qui, oggi. I miei figli sono straordinari e resistenti. Quindi, sono grata e andiamo avanti.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Qual \u00e8 il suo pi\u00f9 grande risultato<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Il mio pi\u00f9 grande risultato personale \u00e8 la mia felicit\u00e0. Ho lavorato molto duramente per essere felice, nonostante le nostre sfide. Ne sono davvero orgogliosa.  \u00c8 una scelta che cerco di fare ogni giorno.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>In che modo la LGMD l'ha influenzata nel diventare la persona che \u00e8 oggi:<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Sento di vivere una vita pi\u00f9 significativa dopo la diagnosi. Amo pi\u00f9 intensamente le mie persone. Ho imparato a rallentare, perch\u00e9 devo farlo, e questo non \u00e8 un brutto modo di vivere la vita. Sono anche grata per l'opportunit\u00e0 di comprendere e provare empatia per coloro che soffrono di malattie croniche, dolore, lutto... tutte quelle malattie invisibili che possono essere facilmente interpretate come pigrizia o mancanza di impegno. Vi vedo e mi dispiace che sia difficile.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Cosa volete che il mondo sappia della LGMD?<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Voglio che il mondo sappia che la LGMD \u00e8 una malattia geneticamente ereditata e non una \"carenza nutrizionale\" o una conseguenza del fatto che non si va in palestra. Non \u00e8 una malattia che le persone scelgono. \u00c8 progressiva e non esiste una cura. Anche se rimanere positivi e attivi pu\u00f2 aiutare, non fermer\u00e0 la progressione. A mio parere, la cosa migliore da dire a una persona affetta da LGMD \u00e8: \"So che \u00e8 difficile e che stai facendo un ottimo lavoro\". Sarebbe meraviglioso trovare un trattamento o una cura in futuro. \u00c8 bene rimanere fiduciosi.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Se la vostra LGMD potesse essere \"curata\" domani, quale sarebbe la prima cosa che vorreste fare?<\/strong>:<\/span><\/p>\n<p><span style=\"color: #000000;\">Portare le mie bambine a scuola a cavalluccio, organizzare una grande festa e fare un giro in bicicletta con la famiglia intorno al nostro lago preferito.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">* * * Per leggere altre \"interviste LGMD Spotlight\" o per proporsi come volontari per una prossima intervista, visitate il nostro sito web. <\/span>a <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.lgmd-info.org\/it\/spotlight-interviews\/\">https:\/\/www.lgmd-info.org\/spotlight-interviews<\/a>\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">* * * Vi invitiamo a mettere MI PIACE, COMMENTARE e CONDIVIDERE questo post per contribuire a sensibilizzare l'opinione pubblica sulla LGMD!<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>LGMD Spotlight Interview Name:\u00a0 \u00a0 Jill\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,35],"tags":[83],"class_list":["post-1651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-individuals-with-lgmd-interviews","category-lgmd2i","tag-lgmd2i-united-states"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lgmd-info.org\/it\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation\" \/>\n<meta property=\"og:description\" content=\"LGMD Spotlight Interview Name:\u00a0 \u00a0 Jill\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lgmd-info.org\/it\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LGMD Awareness Foundation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LGMDawareness\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-08T16:22:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lgmd-info.org\/wp-content\/uploads\/2021\/06\/LGMD-Logo_1200X630.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"dooley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LgmdAwareness\" \/>\n<meta name=\"twitter:site\" content=\"@LgmdAwareness\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"dooley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\"},\"author\":{\"name\":\"dooley\",\"@id\":\"https:\/\/www.lgmd-info.org\/#\/schema\/person\/007755074875959ad5503c1c969678c7\"},\"headline\":\"INDIVIDUAL WITH LGMD: Jill\",\"datePublished\":\"2018-01-08T16:22:50+00:00\",\"dateModified\":\"2018-01-08T16:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\"},\"wordCount\":704,\"publisher\":{\"@id\":\"https:\/\/www.lgmd-info.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"LGMD2i; United States\"],\"articleSection\":[\"Individuals with LGMD - Interviews\",\"LGMD2I\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\",\"url\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\",\"name\":\"INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation\",\"isPartOf\":{\"@id\":\"https:\/\/www.lgmd-info.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2018-01-08T16:22:50+00:00\",\"dateModified\":\"2018-01-08T16:22:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lgmd-info.org\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INDIVIDUAL WITH LGMD: Jill\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lgmd-info.org\/#website\",\"url\":\"https:\/\/www.lgmd-info.org\/\",\"name\":\"LGMD Awareness Foundation\",\"description\":\"Information Hub for the LGMD community\",\"publisher\":{\"@id\":\"https:\/\/www.lgmd-info.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lgmd-info.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lgmd-info.org\/#organization\",\"name\":\"LGMD Awareness Foundation, Inc.\",\"url\":\"https:\/\/www.lgmd-info.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lgmd-info.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lgmd-info.org\/wp-content\/uploads\/2021\/02\/LGMD_Logo.png\",\"contentUrl\":\"https:\/\/lgmd-info.org\/wp-content\/uploads\/2021\/02\/LGMD_Logo.png\",\"width\":208,\"height\":61,\"caption\":\"LGMD Awareness Foundation, Inc.\"},\"image\":{\"@id\":\"https:\/\/www.lgmd-info.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LGMDawareness\/\",\"https:\/\/x.com\/LgmdAwareness\",\"https:\/\/www.instagram.com\/lgmdawareness\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lgmd-info.org\/#\/schema\/person\/007755074875959ad5503c1c969678c7\",\"name\":\"dooley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.lgmd-info.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c87b3b784fd4c1975884b6c3eab282b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c87b3b784fd4c1975884b6c3eab282b5?s=96&d=mm&r=g\",\"caption\":\"dooley\"},\"sameAs\":[\"https:\/\/live-lgmd-2021.pantheonsite.io\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lgmd-info.org\/it\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/","og_locale":"it_IT","og_type":"article","og_title":"INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation","og_description":"LGMD Spotlight Interview Name:\u00a0 \u00a0 Jill\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]","og_url":"https:\/\/www.lgmd-info.org\/it\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/","og_site_name":"LGMD Awareness Foundation","article_publisher":"https:\/\/www.facebook.com\/LGMDawareness\/","article_published_time":"2018-01-08T16:22:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.lgmd-info.org\/wp-content\/uploads\/2021\/06\/LGMD-Logo_1200X630.png","type":"image\/png"}],"author":"dooley","twitter_card":"summary_large_image","twitter_creator":"@LgmdAwareness","twitter_site":"@LgmdAwareness","twitter_misc":{"Written by":"dooley","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#article","isPartOf":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/"},"author":{"name":"dooley","@id":"https:\/\/www.lgmd-info.org\/#\/schema\/person\/007755074875959ad5503c1c969678c7"},"headline":"INDIVIDUAL WITH LGMD: Jill","datePublished":"2018-01-08T16:22:50+00:00","dateModified":"2018-01-08T16:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/"},"wordCount":704,"publisher":{"@id":"https:\/\/www.lgmd-info.org\/#organization"},"image":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage"},"thumbnailUrl":"","keywords":["LGMD2i; United States"],"articleSection":["Individuals with LGMD - Interviews","LGMD2I"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/","url":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/","name":"INDIVIDUAL WITH LGMD: Jill - LGMD Awareness Foundation","isPartOf":{"@id":"https:\/\/www.lgmd-info.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage"},"image":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-01-08T16:22:50+00:00","dateModified":"2018-01-08T16:22:50+00:00","breadcrumb":{"@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.lgmd-info.org\/es\/individuals-with-lgmd-interviews\/2018\/01\/08\/jill-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lgmd-info.org\/pl\/"},{"@type":"ListItem","position":2,"name":"INDIVIDUAL WITH LGMD: Jill"}]},{"@type":"WebSite","@id":"https:\/\/www.lgmd-info.org\/#website","url":"https:\/\/www.lgmd-info.org\/","name":"LGMD Awareness Foundation","description":"Information Hub for the LGMD community","publisher":{"@id":"https:\/\/www.lgmd-info.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lgmd-info.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.lgmd-info.org\/#organization","name":"LGMD Awareness Foundation, Inc.","url":"https:\/\/www.lgmd-info.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lgmd-info.org\/#\/schema\/logo\/image\/","url":"https:\/\/lgmd-info.org\/wp-content\/uploads\/2021\/02\/LGMD_Logo.png","contentUrl":"https:\/\/lgmd-info.org\/wp-content\/uploads\/2021\/02\/LGMD_Logo.png","width":208,"height":61,"caption":"LGMD Awareness Foundation, Inc."},"image":{"@id":"https:\/\/www.lgmd-info.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LGMDawareness\/","https:\/\/x.com\/LgmdAwareness","https:\/\/www.instagram.com\/lgmdawareness\/"]},{"@type":"Person","@id":"https:\/\/www.lgmd-info.org\/#\/schema\/person\/007755074875959ad5503c1c969678c7","name":"dooley","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.lgmd-info.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c87b3b784fd4c1975884b6c3eab282b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c87b3b784fd4c1975884b6c3eab282b5?s=96&d=mm&r=g","caption":"dooley"},"sameAs":["https:\/\/live-lgmd-2021.pantheonsite.io"]}]}},"_links":{"self":[{"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":0,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lgmd-info.org\/it\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}